{"id":39629,"date":"2023-10-19T12:14:54","date_gmt":"2023-10-19T10:14:54","guid":{"rendered":"https:\/\/www.ceoforlifeawards.com\/it\/?p=39629"},"modified":"2024-02-04T23:30:46","modified_gmt":"2024-02-04T22:30:46","slug":"federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile","status":"publish","type":"post","link":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/","title":{"rendered":"PROTTO: <span>&#8220;Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile&#8221;<\/span>"},"content":{"rendered":"<p><strong>FEDERICO PROTTO<\/strong> (<strong><a href=\"https:\/\/www.youtube.com\/watch?v=tELpJuDy4bU\">Guarda la Video Intervista<\/a><\/strong>), Premiato ai CEOforLIFE Awards 2023 nella categoria\u00a0<em>Innovation,<\/em><b>\u00a0<\/b>ha concesso un\u2019intervista nella quale ha discusso l\u2019impatto positivo generato dalla realt\u00e0 CEOforLIFE e la sua vision per la creazione di un Italia pi\u00f9 giusta e sostenibile, proprio come descritto nel claim dell\u2019iniziativa.<\/p>\n<p>Riportiamo di seguito un virgolettato dell\u2019intervista:<\/p>\n<p><em>\u201cLe iniziative promosse dalle aziende e da CEOforLIFE <strong>sono l\u2019unico motore dello sviluppo sostenibile<\/strong> e del fare sistema\u201d<\/em><\/p>\n<p><a class=\"btn btn-default\" href=\"https:\/\/www.youtube.com\/watch?v=tELpJuDy4bU\">VIDEO INTERVISTA<\/a><\/p>\n<p>Guarda la <a href=\"https:\/\/www.youtube.com\/watch?v=tELpJuDy4bU\">VIDEO INTERVISTA<\/a> completa: <a href=\"https:\/\/www.youtube.com\/watch?v=tELpJuDy4bU\">https:\/\/www.youtube.com\/watch?v=tELpJuDy4bU<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FEDERICO PROTTO (Guarda la Video Intervista), Premiato ai CEOforLIFE Awards 2023 nella categoria\u00a0Innovation,\u00a0ha concesso un\u2019intervista nella quale ha discusso l\u2019impatto positivo generato dalla realt\u00e0 CEOforLIFE e la sua vision per la creazione di un Italia pi\u00f9 giusta e sostenibile, proprio come descritto nel claim dell\u2019iniziativa. Riportiamo di seguito un virgolettato dell\u2019intervista: \u201cLe iniziative promosse dalle [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":39630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[378],"tags":[108],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PROTTO: &quot;Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile&quot; - CEOforLIFE - IT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROTTO: &quot;Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile&quot; - CEOforLIFE - IT\" \/>\n<meta property=\"og:description\" content=\"FEDERICO PROTTO (Guarda la Video Intervista), Premiato ai CEOforLIFE Awards 2023 nella categoria\u00a0Innovation,\u00a0ha concesso un\u2019intervista nella quale ha discusso l\u2019impatto positivo generato dalla realt\u00e0 CEOforLIFE e la sua vision per la creazione di un Italia pi\u00f9 giusta e sostenibile, proprio come descritto nel claim dell\u2019iniziativa. Riportiamo di seguito un virgolettato dell\u2019intervista: \u201cLe iniziative promosse dalle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/\" \/>\n<meta property=\"og:site_name\" content=\"CEOforLIFE - IT\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-19T10:14:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-04T22:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"d.digiuseppe@hrcigroup.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/#website\",\"url\":\"https:\/\/www.ceoforlifeawards.com\/it\/\",\"name\":\"CEOforLIFE - IT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ceoforlifeawards.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#primaryimage\",\"url\":\"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg\",\"contentUrl\":\"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#webpage\",\"url\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/\",\"name\":\"PROTTO: \\\"Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile\\\" - CEOforLIFE - IT\",\"isPartOf\":{\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#primaryimage\"},\"datePublished\":\"2023-10-19T10:14:54+00:00\",\"dateModified\":\"2024-02-04T22:30:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/9c2802d81c81cfba5c28677408d38d09\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ceoforlifeawards.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROTTO: &#8220;Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/9c2802d81c81cfba5c28677408d38d09\",\"name\":\"d.digiuseppe@hrcigroup.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b464a83ee224f75bb37df0992d8d2b48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b464a83ee224f75bb37df0992d8d2b48?s=96&d=mm&r=g\",\"caption\":\"d.digiuseppe@hrcigroup.com\"},\"url\":\"https:\/\/www.ceoforlifeawards.com\/it\/blog\/author\/d-digiuseppehrcigroup-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROTTO: \"Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile\" - CEOforLIFE - IT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/","og_locale":"it_IT","og_type":"article","og_title":"PROTTO: \"Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile\" - CEOforLIFE - IT","og_description":"FEDERICO PROTTO (Guarda la Video Intervista), Premiato ai CEOforLIFE Awards 2023 nella categoria\u00a0Innovation,\u00a0ha concesso un\u2019intervista nella quale ha discusso l\u2019impatto positivo generato dalla realt\u00e0 CEOforLIFE e la sua vision per la creazione di un Italia pi\u00f9 giusta e sostenibile, proprio come descritto nel claim dell\u2019iniziativa. Riportiamo di seguito un virgolettato dell\u2019intervista: \u201cLe iniziative promosse dalle [&hellip;]","og_url":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/","og_site_name":"CEOforLIFE - IT","article_published_time":"2023-10-19T10:14:54+00:00","article_modified_time":"2024-02-04T22:30:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"d.digiuseppe@hrcigroup.com","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.ceoforlifeawards.com\/it\/#website","url":"https:\/\/www.ceoforlifeawards.com\/it\/","name":"CEOforLIFE - IT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ceoforlifeawards.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#primaryimage","url":"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg","contentUrl":"https:\/\/www.ceoforlifeawards.com\/it\/wp-content\/uploads\/sites\/3\/2023\/11\/Immagine2-7-scaled.jpg","width":2560,"height":1707},{"@type":"WebPage","@id":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#webpage","url":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/","name":"PROTTO: \"Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile\" - CEOforLIFE - IT","isPartOf":{"@id":"https:\/\/www.ceoforlifeawards.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#primaryimage"},"datePublished":"2023-10-19T10:14:54+00:00","dateModified":"2024-02-04T22:30:46+00:00","author":{"@id":"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/9c2802d81c81cfba5c28677408d38d09"},"breadcrumb":{"@id":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/federico-protto-ai-ceoforlife-awards-2023-le-iniziative-di-ceoforlife-sono-il-motore-dello-sviluppo-sostenibile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ceoforlifeawards.com\/it\/"},{"@type":"ListItem","position":2,"name":"PROTTO: &#8220;Le iniziative di CEOforLIFE sono il motore dello sviluppo sostenibile&#8221;"}]},{"@type":"Person","@id":"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/9c2802d81c81cfba5c28677408d38d09","name":"d.digiuseppe@hrcigroup.com","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ceoforlifeawards.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b464a83ee224f75bb37df0992d8d2b48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b464a83ee224f75bb37df0992d8d2b48?s=96&d=mm&r=g","caption":"d.digiuseppe@hrcigroup.com"},"url":"https:\/\/www.ceoforlifeawards.com\/it\/blog\/author\/d-digiuseppehrcigroup-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/posts\/39629"}],"collection":[{"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/comments?post=39629"}],"version-history":[{"count":4,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/posts\/39629\/revisions"}],"predecessor-version":[{"id":44396,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/posts\/39629\/revisions\/44396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/media\/39630"}],"wp:attachment":[{"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/media?parent=39629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/categories?post=39629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ceoforlifeawards.com\/it\/wp-json\/wp\/v2\/tags?post=39629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}